{"id":3541,"date":"2017-04-21T15:44:03","date_gmt":"2017-04-21T08:44:03","guid":{"rendered":"http:\/\/journal.rmutp.ac.th\/rmutphuso\/?p=3541"},"modified":"2017-04-21T15:44:03","modified_gmt":"2017-04-21T08:44:03","slug":"%e0%b8%a7%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%88%e0%b8%b1%e0%b8%a2-2","status":"publish","type":"post","link":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/2017\/04\/%e0%b8%a7%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%a7%e0%b8%b4%e0%b8%88%e0%b8%b1%e0%b8%a2-2\/","title":{"rendered":"\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e21\u0e17\u0e23.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e21\u0e19\u0e38\u0e29\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e41\u0e08\u0e49\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07"},"content":{"rendered":"<h3>\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e21\u0e17\u0e23.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e21\u0e19\u0e38\u0e29\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u00a0\u0e02\u0e2d\u0e22\u0e01\u0e40\u0e25\u0e34\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e43\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02 [ 1], [ 2], [3] \u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e09\u0e1a\u0e31\u0e1a 1 \u0e21.\u0e04.-\u0e21\u0e34.\u0e22. 2559 \u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e09\u0e1a\u0e31\u0e1a 2 \u0e01.\u0e04.-\u0e18.\u0e04.2560 \u00a0\u0e2b\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2f \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07 \u00a0(APA style) \u00a0\u0e42\u0e14\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e43\u0e0a\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u0e1b\u0e35\u0e17\u0e35\u0e48 2 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 \u00a01 \u00a0\u0e21.\u0e04.-\u0e21\u0e34.\u0e22. 2560 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e21\u0e17\u0e23.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23 \u0e2a\u0e32\u0e02\u0e32\u0e21\u0e19\u0e38\u0e29\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u00a0\u0e02\u0e2d\u0e22\u0e01\u0e40\u0e25\u0e34\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e43\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02 [ 1], [ 2], [3] \u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e09\u0e1a\u0e31\u0e1a 1 \u0e21.\u0e04.-\u0e21\u0e34.\u0e22. 2559 \u0e1b\u0e35\u0e17\u0e35\u0e48 1 \u0e09\u0e1a\u0e31\u0e1a 2 \u0e01.\u0e04.-\u0e18.\u0e04.2560 \u00a0\u0e2b\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2f \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07 \u00a0(APA style) \u00a0\u0e42\u0e14\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e43\u0e0a\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u0e1b\u0e35\u0e17\u0e35\u0e48 2 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 \u00a01 \u00a0\u0e21.\u0e04.-\u0e21\u0e34.\u0e22. 2560 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/posts\/3541"}],"collection":[{"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/comments?post=3541"}],"version-history":[{"count":2,"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/posts\/3541\/revisions"}],"predecessor-version":[{"id":3543,"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/posts\/3541\/revisions\/3543"}],"wp:attachment":[{"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/media?parent=3541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/categories?post=3541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/journal.rmutp.ac.th\/rmutphuso\/wp-json\/wp\/v2\/tags?post=3541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}